{"id":21107,"date":"2025-02-26T11:26:08","date_gmt":"2025-02-26T16:26:08","guid":{"rendered":"\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front.png"},"modified":"2025-05-15T16:27:46","modified_gmt":"2025-05-15T20:27:46","slug":"ll-hydrate-front-2","status":"inherit","type":"attachment","link":"\/es\/productcoach\/ll-hydrate-front-2\/","title":{"rendered":"LL HYDRATE Front"},"author":191432657,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"class_list":["post-21107","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https://d1jeyrxw15fk4e.cloudfront.net/es/https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-300x300.png\" class=\"attachment-medium size-medium\" alt=\"Hydrate scoops and sticks mockup - all flavors\" srcset=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-300x300.png 300w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-150x150.png 150w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-768x768.png 768w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-480x480.png 480w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Hydrate scoops and sticks mockup - all flavors","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":800,"file":"2025\/02\/LL-HYDRATE-Front.png","filesize":337904,"sizes":{"medium":{"file":"LL-HYDRATE-Front-300x300.png","width":300,"height":300,"filesize":69998,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-300x300.png"},"thumbnail":{"file":"LL-HYDRATE-Front-150x150.png","width":150,"height":150,"filesize":22045,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-150x150.png"},"medium_large":{"file":"LL-HYDRATE-Front-768x768.png","width":768,"height":768,"filesize":315643,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-768x768.png"},"et-pb-post-main-image":{"file":"LL-HYDRATE-Front-400x250.png","width":400,"height":250,"filesize":110132,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-400x250.png"},"et-pb-post-main-image-fullwidth":{"file":"LL-HYDRATE-Front-800x675.png","width":800,"height":675,"filesize":327957,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-800x675.png"},"et-pb-portfolio-image":{"file":"LL-HYDRATE-Front-400x284.png","width":400,"height":284,"filesize":110431,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-400x284.png"},"et-pb-portfolio-module-image":{"file":"LL-HYDRATE-Front-510x382.png","width":510,"height":382,"filesize":160698,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-510x382.png"},"et-pb-gallery-module-image-portrait":{"file":"LL-HYDRATE-Front-400x516.png","width":400,"height":516,"filesize":144935,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-400x516.png"},"et-pb-image--responsive--phone":{"file":"LL-HYDRATE-Front-480x480.png","width":480,"height":480,"filesize":149219,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front-480x480.png"},"full":{"file":"LL-HYDRATE-Front.png","width":800,"height":800,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":15610,"source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/02\/LL-HYDRATE-Front.png","filename":"LL-HYDRATE-Front.png","filesize":337904,"_links":{"self":[{"href":"https:\/\/iam.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media\/21107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iam.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/iam.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/iam.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/users\/191432657"}],"replies":[{"embeddable":true,"href":"https:\/\/iam.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/comments?post=21107"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":15610,"href":"https:\/\/iam.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/pages\/15610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}